{"id":8340,"date":"2024-03-01T18:16:39","date_gmt":"2024-03-01T18:16:39","guid":{"rendered":"https:\/\/amiti.org.mx\/?p=8340"},"modified":"2024-03-06T18:17:47","modified_gmt":"2024-03-06T18:17:47","slug":"la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes","status":"publish","type":"post","link":"https:\/\/amiti.org.mx\/en\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/","title":{"rendered":"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><em>Miembros de la Coalici\u00f3n por la Salud Digital de M\u00e9xico (CoSaDiM) y el Diputado \u00c9ctor Jaime Ram\u00edrez Barba, secretario de la Comisi\u00f3n de Salud de la C\u00e1mara de Diputados, analizaron propuestas para el desarrollo de la Salud Digital en el pa\u00eds.<\/em><\/li>\n<\/ul>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ciudad de M\u00e9xico, a 29 de febrero de 2024<\/strong>.- En medio de una creciente demanda de servicios de salud, derivados del envejecimiento de la poblaci\u00f3n y estilos de vida poco sanos que promueven el desarrollo enfermedades cr\u00f3nico-degenerativas, la adopci\u00f3n de tecnolog\u00edas de salud digitales puede facilitar un mejor y m\u00e1s oportuno acceso a la atenci\u00f3n m\u00e9dica en beneficio del bienestar y la calidad de vida de los pacientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco del Conversatorio <em>\u201cAvances y Desaf\u00edos de la Digitalizaci\u00f3n de la Salud en M\u00e9xico\u201d<\/em>, organizado por la Coalici\u00f3n por la Salud Digital de M\u00e9xico (CoSaDiM) y el Diputado \u00c9ctor Jaime Ram\u00edrez Barba, secretario de la Comisi\u00f3n de Salud de la C\u00e1mara de Diputados, se expuso que la salud digital est\u00e1 desempe\u00f1ando un papel cada vez m\u00e1s importante en los sistemas sanitarios a trav\u00e9s de registros m\u00e9dicos electr\u00f3nicos, el uso de datos poblacionales para el seguimiento, la formulaci\u00f3n de pol\u00edticas p\u00fablicas y la integraci\u00f3n de herramientas digitales como la telemedicina en la atenci\u00f3n cl\u00ednica de rutina.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"606\" src=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto2-1024x606.jpeg\" alt=\"\" class=\"wp-image-8341\" style=\"width:480px;height:auto\" srcset=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto2-1024x606.jpeg 1024w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto2-300x178.jpeg 300w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto2-768x455.jpeg 768w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto2.jpeg 1088w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, para que la transformaci\u00f3n digital sea una realidad, es necesario el trabajo en equipo entre todos los actores involucrados en el ecosistema sanitario para poder desarrollar la infraestructura, las estrategias y el marco regulatorio que siente las bases para la evoluci\u00f3n de la salud p\u00fablica en el pa\u00eds a trav\u00e9s del uso de la tecnolog\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la sesi\u00f3n, el <strong>Dr. Santos Uscanga<\/strong>, representante de la Asociaci\u00f3n Mexicana de Lucha Contra el C\u00e1ncer (AMLCC), mencion\u00f3 que el uso de la tecnolog\u00eda brindar\u00e1 a un mayor n\u00famero de pacientes la oportunidad de acceder a los servicios de salud y permitir\u00e1 obtener informaci\u00f3n sobre la calidad de la atenci\u00f3n m\u00e9dica de utilidad en la toman de decisiones para mejorarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siendo el paciente el centro de atenci\u00f3n de la salud digital, <strong>Osiris L\u00f3pez<\/strong>, Gerente de Vinculaci\u00f3n del Sector Salud de GS1 M\u00e9xico, enfatiz\u00f3 la necesidad de lograr y mejorar la interoperabilidad de todos los involucrados, creando un entorno altamente eficiente, sostenible y colaborativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cMediante el desarrollo de soluciones tecnol\u00f3gicas, como los c\u00f3digos bidimensionales hasta cat\u00e1logos electr\u00f3nicos de \u00faltima generaci\u00f3n como Syncfon\u00eda, podemos contribuir a lograr la interoperabilidad del ecosistema de salud a trav\u00e9s de datos de calidad estandarizados, homologados y completos de los productos farmac\u00e9uticos, lo cual es un factor clave para para la implementaci\u00f3n de la Receta M\u00e9dica Electr\u00f3nica y el Expediente Cl\u00ednico Electr\u00f3nico\u201d, <\/em>expuso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior tiene grandes ventajas, entre ellas brindar la terapia espec\u00edfica en el momento adecuado a cada paciente, se fortalecer\u00e1 la producci\u00f3n y abastecimiento de medicamentos, se tendr\u00e1 un mejor control de la cadena de suministro y se fomentar\u00e1 una industria que genera m\u00e1s de 55 mil empleos especializados, precis\u00f3 por su parte <strong>Juan de Villafranca<\/strong>, presidente ejecutivo de la Asociaci\u00f3n Mexicana de Laboratorios Farmac\u00e9uticos (AMELAF).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su participaci\u00f3n, <strong>Luis Espinosa<\/strong>, cofundador de Mi Receta Digital, destac\u00f3 el importante rol que tiene el m\u00e9dico en la adopci\u00f3n y uso de la tecnolog\u00eda en favor de su pr\u00e1ctica cl\u00ednica y en beneficio de<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">los pacientes. <em>\u201cEl paciente ser\u00e1 el protagonista de la salud digital, mediante el impulso de los m\u00e9dicos en la adopci\u00f3n de la tecnolog\u00eda para conseguir la transformaci\u00f3n de la salud en M\u00e9xico\u201d, <\/em>asegur\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los grandes retos es el desarrollo que garanticen la protecci\u00f3n de datos en los pacientes, y en ese sentido <strong>Marcos Pascual<\/strong>, director Comercial de la Asociaci\u00f3n Nacional de Farmacias de M\u00e9xico, A.C. (ANAFARMEX), se\u00f1al\u00f3 que es importante que ellos tengan la certeza y la seguridad de que el \u00fanico due\u00f1o de su informaci\u00f3n es \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEn M\u00e9xico es importante darle la confianza al paciente de que su informaci\u00f3n personal ser\u00e1 resguardada y tratada correctamente. Existen mecanismos como el denominado ARCO (Acceso, Rectificaci\u00f3n, Cancelaci\u00f3n y Oposici\u00f3n), as\u00ed como instituciones que proteger\u00e1n y velaran por el derecho a su informaci\u00f3n como es el caso del Instituto Nacional de Acceso a la Informaci\u00f3n (INAI). Por ello, el paciente debe contar con un instrumento tecnol\u00f3gico \u00e1gil, seguro y de f\u00e1cil implementaci\u00f3n\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, <strong>Adriana Garc\u00eda<\/strong>, l\u00edder del Comit\u00e9 de Salud Digital de la Asociaci\u00f3n Mexicana de la Industria de Tecnolog\u00edas de Informaci\u00f3n (AMITI), consider\u00f3 que contar con reglas establecidas para el uso y la transferencia de datos de salud ayudar\u00e1 a los pacientes a tener acceso a mejores opciones y condiciones, que impactar\u00e1n positivamente en su atenci\u00f3n y cuidado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cLos Unicornios de la Salud aprovechan la integraci\u00f3n de informaci\u00f3n para impactar en los planes de salud, en la precisi\u00f3n de los diagn\u00f3sticos de ciertas enfermedades y en el manejo de tratamientos (medicina personalizada), entre otros. Y la siguiente ola de innovaci\u00f3n que brindar\u00e1 el uso de algoritmos con Inteligencia Artificial aplicados a la salud, demandar\u00e1 que los pa\u00edses est\u00e9n mejor preparados para el intercambio de datos, por lo que no podemos seguir posponiendo el lograr acuerdos\u201d, <\/em>coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pablo Corona<\/strong>, presidente de la Asociaci\u00f3n de Internet MX, reconoci\u00f3 que \u201c<em>a\u00fan hay una brecha significativa en la aplicaci\u00f3n de la tecnolog\u00eda de manera generalizada, principalmente por la falta de presupuesto, estandarizaci\u00f3n de plataformas digitales, limitaciones en el acceso a Internet y servicios en algunas regiones del pa\u00eds que permitan la interoperabilidad, considerando aspectos relevantes como la privacidad y la seguridad de la informaci\u00f3n\u201d. <\/em>Tambi\u00e9n, precis\u00f3 la necesidad de trabajar en la concientizaci\u00f3n, capacitaci\u00f3n y transferencia de capacidades para el uso adecuado de estas tecnolog\u00edas en favor de los usuarios del sistema m\u00e9dico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, la urgente necesidad de lograr el compromiso y colaboraci\u00f3n entre gobierno, industria farmac\u00e9utica, organismos sanitarios, empresas del sector salud y Health Tech para desarrollar soluciones en pro de alcanzar el principio m\u00e1ximo que es el bienestar y la salud para todos los mexicanos, y colaborar para lograr los objetivos de desarrollo sostenible y el acceso universal a la salud para 2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, <strong>\u00c9ctor Jaime Ram\u00edrez Barba<\/strong>, secretario de la Comisi\u00f3n de Salud de la C\u00e1mara de Diputados, expres\u00f3 que en el Congreso y particularmente en la C\u00e1mara de Diputados durante la actual legislatura, hubo avances importantes en materia de salud digital, en la Comisi\u00f3n de Salud se analizaron y aprobaron dos proyectos relevantes en materia de receta m\u00e9dica electr\u00f3nica y teleconsulta m\u00e9dica, que ya est\u00e1n en poder de la Mesa Directiva de esta C\u00e1mara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La adopci\u00f3n de las herramientas de salud digital en nuestro sistema de salud nos permitir\u00e1 ampliar la cobertura y mejorar el acceso y la calidad de la atenci\u00f3n m\u00e9dica para toda la poblaci\u00f3n, por ello,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">es valioso mantener un di\u00e1logo permanente con todos los actores del sistema, de manera que con su participaci\u00f3n construyamos un sistema de salud eficaz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La salud digital ya est\u00e1 aqu\u00ed, a nuestra disposici\u00f3n, y lo que nos toca es continuar impulsando su marco regulatorio, para que las herramientas tecnol\u00f3gicas en los servicios de salud est\u00e9n al alcance de todos.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h6 class=\"wp-block-heading has-small-font-size\"><br><strong>Sobre la CoSaDiM<\/strong><\/h6>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Grupo de trabajo conformado por instituciones clave del ecosistema de salud cuyo objetivo es impulsar la transformaci\u00f3n y el fortalecimiento del Sistema de Salud del pa\u00eds a trav\u00e9s de la digitalizaci\u00f3n. Su misi\u00f3n es contribuir en la construcci\u00f3n de un sistema de salud digital a trav\u00e9s de propuestas que conduzcan a la implementaci\u00f3n de buenas pr\u00e1cticas de Tecnolog\u00edas de la Informaci\u00f3n y Comunicaciones (TICs) para mejorar la accesibilidad a servicios de salud eficientes, efectivos y de calidad, colaborar en el empoderamiento de los pacientes, as\u00ed como contribuir en la creaci\u00f3n de un sistema de salud equitativo, eficiente y sostenible. La Presidencia para el ciclo 2023-2024 est\u00e1 a cargo de Juan Carlos Molina Robledo, Director General de GS1 M\u00e9xico.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico, a 29 de febrero de 2024.- En medio de una creciente demanda de servicios de salud, derivados del envejecimiento de la poblaci\u00f3n y estilos de vida poco sanos que promueven el desarrollo enfermedades cr\u00f3nico-degenerativas, la adopci\u00f3n de tecnolog\u00edas de salud digitales puede facilitar un mejor y m\u00e1s oportuno acceso a la atenci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":148,"featured_media":8342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-8340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-amiti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes - AMITI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amiti.org.mx\/en\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes - AMITI\" \/>\n<meta property=\"og:description\" content=\"Ciudad de M\u00e9xico, a 29 de febrero de 2024.- En medio de una creciente demanda de servicios de salud, derivados del envejecimiento de la poblaci\u00f3n y estilos de vida poco sanos que promueven el desarrollo enfermedades cr\u00f3nico-degenerativas, la adopci\u00f3n de tecnolog\u00edas de salud digitales puede facilitar un mejor y m\u00e1s oportuno acceso a la atenci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amiti.org.mx\/en\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/\" \/>\n<meta property=\"og:site_name\" content=\"AMITI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AMITIMex\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T18:16:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T18:17:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1007\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heidy-O\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AMITI_Mex\" \/>\n<meta name=\"twitter:site\" content=\"@AMITI_Mex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heidy-O\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/\"},\"author\":{\"name\":\"Heidy-O\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/person\\\/09fd614b7d440b5ba06c0480ed768000\"},\"headline\":\"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes\",\"datePublished\":\"2024-03-01T18:16:39+00:00\",\"dateModified\":\"2024-03-06T18:17:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/\"},\"wordCount\":1451,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ConversatorioSalud-Foto1.jpeg\",\"articleSection\":[\"Noticias AMITI\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/\",\"name\":\"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes - AMITI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ConversatorioSalud-Foto1.jpeg\",\"datePublished\":\"2024-03-01T18:16:39+00:00\",\"dateModified\":\"2024-03-06T18:17:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ConversatorioSalud-Foto1.jpeg\",\"contentUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ConversatorioSalud-Foto1.jpeg\",\"width\":1007,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/8340\\\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amiti.org.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#website\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/\",\"name\":\"AMITI\",\"description\":\"Mejores empresas TI para M\u00e9xico\",\"publisher\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amiti.org.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#organization\",\"name\":\"AMITI\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Amiti_CMYK.png\",\"contentUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Amiti_CMYK.png\",\"width\":1161,\"height\":458,\"caption\":\"AMITI\"},\"image\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AMITIMex\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/AMITI_Mex\",\"https:\\\/\\\/www.instagram.com\\\/amiti_mex\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/amiti-mex\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCaBdZB-k6j-lCH-eTCbLGJw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/person\\\/09fd614b7d440b5ba06c0480ed768000\",\"name\":\"Heidy-O\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g\",\"caption\":\"Heidy-O\"},\"url\":\"https:\\\/\\\/amiti.org.mx\\\/en\\\/author\\\/heidy-o\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes - AMITI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amiti.org.mx\/en\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/","og_locale":"en_US","og_type":"article","og_title":"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes - AMITI","og_description":"Ciudad de M\u00e9xico, a 29 de febrero de 2024.- En medio de una creciente demanda de servicios de salud, derivados del envejecimiento de la poblaci\u00f3n y estilos de vida poco sanos que promueven el desarrollo enfermedades cr\u00f3nico-degenerativas, la adopci\u00f3n de tecnolog\u00edas de salud digitales puede facilitar un mejor y m\u00e1s oportuno acceso a la atenci\u00f3n [&hellip;]","og_url":"https:\/\/amiti.org.mx\/en\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/","og_site_name":"AMITI","article_publisher":"https:\/\/www.facebook.com\/AMITIMex\/?locale=es_LA","article_published_time":"2024-03-01T18:16:39+00:00","article_modified_time":"2024-03-06T18:17:47+00:00","og_image":[{"width":1007,"height":594,"url":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto1.jpeg","type":"image\/jpeg"}],"author":"Heidy-O","twitter_card":"summary_large_image","twitter_creator":"@AMITI_Mex","twitter_site":"@AMITI_Mex","twitter_misc":{"Written by":"Heidy-O","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/#article","isPartOf":{"@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/"},"author":{"name":"Heidy-O","@id":"https:\/\/amiti.org.mx\/#\/schema\/person\/09fd614b7d440b5ba06c0480ed768000"},"headline":"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes","datePublished":"2024-03-01T18:16:39+00:00","dateModified":"2024-03-06T18:17:47+00:00","mainEntityOfPage":{"@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/"},"wordCount":1451,"commentCount":0,"publisher":{"@id":"https:\/\/amiti.org.mx\/#organization"},"image":{"@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/#primaryimage"},"thumbnailUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto1.jpeg","articleSection":["Noticias AMITI"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/","url":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/","name":"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes - AMITI","isPartOf":{"@id":"https:\/\/amiti.org.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/#primaryimage"},"image":{"@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/#primaryimage"},"thumbnailUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto1.jpeg","datePublished":"2024-03-01T18:16:39+00:00","dateModified":"2024-03-06T18:17:47+00:00","breadcrumb":{"@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/#primaryimage","url":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto1.jpeg","contentUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/03\/ConversatorioSalud-Foto1.jpeg","width":1007,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/amiti.org.mx\/8340\/la-adopcion-de-herramientas-tecnologicas-en-el-sector-salud-mexicano-permitira-mejorar-la-atencion-a-los-pacientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amiti.org.mx\/"},{"@type":"ListItem","position":2,"name":"La adopci\u00f3n de herramientas tecnol\u00f3gicas en el sector salud mexicano permitir\u00e1 mejorar la atenci\u00f3n a los pacientes"}]},{"@type":"WebSite","@id":"https:\/\/amiti.org.mx\/#website","url":"https:\/\/amiti.org.mx\/","name":"AMITI","description":"Mejores empresas TI para M\u00e9xico","publisher":{"@id":"https:\/\/amiti.org.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amiti.org.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/amiti.org.mx\/#organization","name":"AMITI","url":"https:\/\/amiti.org.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/amiti.org.mx\/#\/schema\/logo\/image\/","url":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/09\/Amiti_CMYK.png","contentUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/09\/Amiti_CMYK.png","width":1161,"height":458,"caption":"AMITI"},"image":{"@id":"https:\/\/amiti.org.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AMITIMex\/?locale=es_LA","https:\/\/x.com\/AMITI_Mex","https:\/\/www.instagram.com\/amiti_mex\/","https:\/\/www.linkedin.com\/company\/amiti-mex\/","https:\/\/www.youtube.com\/channel\/UCaBdZB-k6j-lCH-eTCbLGJw"]},{"@type":"Person","@id":"https:\/\/amiti.org.mx\/#\/schema\/person\/09fd614b7d440b5ba06c0480ed768000","name":"Heidy-O","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g","caption":"Heidy-O"},"url":"https:\/\/amiti.org.mx\/en\/author\/heidy-o\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:16:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts\/8340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/users\/148"}],"replies":[{"embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/comments?post=8340"}],"version-history":[{"count":4,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts\/8340\/revisions"}],"predecessor-version":[{"id":8346,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts\/8340\/revisions\/8346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/media\/8342"}],"wp:attachment":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/media?parent=8340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/categories?post=8340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/tags?post=8340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}