{"id":12668,"date":"2025-05-19T23:17:39","date_gmt":"2025-05-19T23:17:39","guid":{"rendered":"https:\/\/amiti.org.mx\/?p=12668"},"modified":"2025-05-29T23:51:17","modified_gmt":"2025-05-29T23:51:17","slug":"amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas","status":"publish","type":"post","link":"https:\/\/amiti.org.mx\/en\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/","title":{"rendered":"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas"},"content":{"rendered":"<p>La Asociaci\u00f3n Mexicana de la Industria de Tecnolog\u00edas de la Informaci\u00f3n (AMITI) particip\u00f3 al pasado 15 de mayo en el Taller de la <strong>Organizaci\u00f3n Mundial del Comercio (OMC) sobre la \u00abMoratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas\u00bb. <\/strong>La Directora General de AMITI, Sof\u00eda P\u00e9rez Gasque, intervino en el panel <strong><em>\u201cPerspectivas del Sector Privado\u201d<\/em><\/strong>, reafirmando el compromiso del sector tecnol\u00f3gico mexicano con el comercio digital abierto, inclusivo y competitivo.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"568\" src=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_1-1024x568.png\" alt=\"\" class=\"wp-image-12670\" style=\"width:624px;height:auto\" srcset=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_1-1024x568.png 1024w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_1-300x166.png 300w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_1-768x426.png 768w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_1-1536x852.png 1536w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_1-18x10.png 18w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_1.png 1876w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Durante su participaci\u00f3n, Sof\u00eda P\u00e9rez Gasque destac\u00f3 que la moratoria de la OMC no es solamente una cuesti\u00f3n t\u00e9cnica de comercio, sino un elemento clave para la inclusi\u00f3n digital, la resiliencia econ\u00f3mica y la competitividad regional. Representando a m\u00e1s de 150 empresas l\u00edderes del sector tecnol\u00f3gico en M\u00e9xico, AMITI expres\u00f3 un firme respaldo a la continuidad de esta medida.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"715\" data-id=\"12672\" src=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_2-1024x715.png\" alt=\"\" class=\"wp-image-12672\" srcset=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_2-1024x715.png 1024w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_2-300x210.png 300w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_2-768x536.png 768w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_2-1536x1073.png 1536w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_2-18x12.png 18w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_2.png 1873w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"360\" height=\"360\" data-id=\"12669\" src=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC.jpg\" alt=\"\" class=\"wp-image-12669\" srcset=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC.jpg 360w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC-300x300.jpg 300w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC-150x150.jpg 150w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC-12x12.jpg 12w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"564\" data-id=\"12671\" src=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_3-1024x564.png\" alt=\"\" class=\"wp-image-12671\" srcset=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_3-1024x564.png 1024w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_3-300x165.png 300w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_3-768x423.png 768w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_3-1536x845.png 1536w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_3-18x10.png 18w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC_3.png 1873w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Asimismo, subray\u00f3 que la OMC es hoy uno de los foros m\u00e1s relevantes para definir las reglas del juego en el comercio digital. Para pa\u00edses como M\u00e9xico \u2014con una creciente industria de tecnolog\u00edas de la informaci\u00f3n y servicios digitales\u2014, participar activamente en este espacio es estrat\u00e9gico para proteger y potenciar a sus empresas tecnol\u00f3gicas.<\/p>\n\n\n\n<p>La Directora General expuso seis razones clave por las que el sector privado mexicano apoya la extensi\u00f3n de esta moratoria:<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li><strong>Facilitaci\u00f3n del comercio digital transfronterizo<\/strong>, en beneficio de miles de MiPyMEs que dependen de flujos digitales abiertos para acceder a mercados globales.<\/li>\n\n\n\n<li><strong>Impulso al desarrollo regional e inclusivo<\/strong>, con crecimientos destacados en estados como Oaxaca, Sinaloa, Nayarit e Hidalgo.<\/li>\n\n\n\n<li><strong>Fomento a la innovaci\u00f3n y productividad<\/strong>, permitiendo que las empresas inviertan en nuevas tecnolog\u00edas y productos digitales sin cargas adicionales.<\/li>\n\n\n\n<li><strong>Certeza jur\u00eddica y previsibilidad comercia<\/strong>l, frente al riesgo de un sistema fragmentado de aranceles unilaterales.<\/li>\n\n\n\n<li><strong>Coherencia con los acuerdos comerciales de M\u00e9xico<\/strong>, como el T-MEC, que proh\u00edben la imposici\u00f3n de derechos aduaneros sobre productos digitales.<\/li>\n\n\n\n<li>Reducci\u00f3n de disparidades econ\u00f3micas, permitiendo la participaci\u00f3n global de peque\u00f1as empresas, emprendimientos liderados por mujeres y regiones menos favorecidas.<\/li>\n<\/ol>\n\n\n\n<p>AMITI hizo un llamado a la OMC y a sus pa\u00edses miembros para continuar escuchando activamente al sector privado, especialmente en econom\u00edas emergentes, con el fin de construir pol\u00edticas de comercio digital justas, inclusivas y preparadas para el futuro.<\/p>\n\n\n\n<p><em>\u201cLa cooperaci\u00f3n internacional es clave para el fortalecimiento de la econom\u00eda digital global. En AMITI estamos listas y listos para colaborar en la construcci\u00f3n de capacidades, el intercambio de conocimiento y el desarrollo de un entorno digital competitivo y sostenible\u201d,<\/em> concluy\u00f3 Sof\u00eda P\u00e9rez Gasque.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Mexicana de la Industria de Tecnolog\u00edas de la Informaci\u00f3n (AMITI) particip\u00f3 al pasado 15 de mayo en el Taller de la Organizaci\u00f3n Mundial del Comercio (OMC) sobre la \u00abMoratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas\u00bb. La Directora General de AMITI, Sof\u00eda P\u00e9rez Gasque, intervino en el panel \u201cPerspectivas del Sector Privado\u201d, reafirmando [&hellip;]<\/p>\n","protected":false},"author":148,"featured_media":12669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-12668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-amiti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas - AMITI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amiti.org.mx\/en\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas - AMITI\" \/>\n<meta property=\"og:description\" content=\"La Asociaci\u00f3n Mexicana de la Industria de Tecnolog\u00edas de la Informaci\u00f3n (AMITI) particip\u00f3 al pasado 15 de mayo en el Taller de la Organizaci\u00f3n Mundial del Comercio (OMC) sobre la \u00abMoratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas\u00bb. La Directora General de AMITI, Sof\u00eda P\u00e9rez Gasque, intervino en el panel \u201cPerspectivas del Sector Privado\u201d, reafirmando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amiti.org.mx\/en\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/\" \/>\n<meta property=\"og:site_name\" content=\"AMITI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AMITIMex\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-19T23:17:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T23:51:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heidy-O\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AMITI_Mex\" \/>\n<meta name=\"twitter:site\" content=\"@AMITI_Mex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heidy-O\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/\"},\"author\":{\"name\":\"Heidy-O\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/person\\\/09fd614b7d440b5ba06c0480ed768000\"},\"headline\":\"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas\",\"datePublished\":\"2025-05-19T23:17:39+00:00\",\"dateModified\":\"2025-05-29T23:51:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/\"},\"wordCount\":460,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/OMC.jpg\",\"articleSection\":[\"Noticias AMITI\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/\",\"name\":\"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas - AMITI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/OMC.jpg\",\"datePublished\":\"2025-05-19T23:17:39+00:00\",\"dateModified\":\"2025-05-29T23:51:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/OMC.jpg\",\"contentUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/OMC.jpg\",\"width\":360,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12668\\\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amiti.org.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#website\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/\",\"name\":\"AMITI\",\"description\":\"Mejores empresas TI para M\u00e9xico\",\"publisher\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amiti.org.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#organization\",\"name\":\"AMITI\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Amiti_CMYK.png\",\"contentUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Amiti_CMYK.png\",\"width\":1161,\"height\":458,\"caption\":\"AMITI\"},\"image\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AMITIMex\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/AMITI_Mex\",\"https:\\\/\\\/www.instagram.com\\\/amiti_mex\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/amiti-mex\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCaBdZB-k6j-lCH-eTCbLGJw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/person\\\/09fd614b7d440b5ba06c0480ed768000\",\"name\":\"Heidy-O\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g\",\"caption\":\"Heidy-O\"},\"url\":\"https:\\\/\\\/amiti.org.mx\\\/en\\\/author\\\/heidy-o\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas - AMITI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amiti.org.mx\/en\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/","og_locale":"en_US","og_type":"article","og_title":"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas - AMITI","og_description":"La Asociaci\u00f3n Mexicana de la Industria de Tecnolog\u00edas de la Informaci\u00f3n (AMITI) particip\u00f3 al pasado 15 de mayo en el Taller de la Organizaci\u00f3n Mundial del Comercio (OMC) sobre la \u00abMoratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas\u00bb. La Directora General de AMITI, Sof\u00eda P\u00e9rez Gasque, intervino en el panel \u201cPerspectivas del Sector Privado\u201d, reafirmando [&hellip;]","og_url":"https:\/\/amiti.org.mx\/en\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/","og_site_name":"AMITI","article_publisher":"https:\/\/www.facebook.com\/AMITIMex\/?locale=es_LA","article_published_time":"2025-05-19T23:17:39+00:00","article_modified_time":"2025-05-29T23:51:17+00:00","og_image":[{"width":360,"height":360,"url":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC.jpg","type":"image\/jpeg"}],"author":"Heidy-O","twitter_card":"summary_large_image","twitter_creator":"@AMITI_Mex","twitter_site":"@AMITI_Mex","twitter_misc":{"Written by":"Heidy-O","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/#article","isPartOf":{"@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/"},"author":{"name":"Heidy-O","@id":"https:\/\/amiti.org.mx\/#\/schema\/person\/09fd614b7d440b5ba06c0480ed768000"},"headline":"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas","datePublished":"2025-05-19T23:17:39+00:00","dateModified":"2025-05-29T23:51:17+00:00","mainEntityOfPage":{"@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/"},"wordCount":460,"commentCount":0,"publisher":{"@id":"https:\/\/amiti.org.mx\/#organization"},"image":{"@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/#primaryimage"},"thumbnailUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC.jpg","articleSection":["Noticias AMITI"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/","url":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/","name":"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas - AMITI","isPartOf":{"@id":"https:\/\/amiti.org.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/#primaryimage"},"image":{"@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/#primaryimage"},"thumbnailUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC.jpg","datePublished":"2025-05-19T23:17:39+00:00","dateModified":"2025-05-29T23:51:17+00:00","breadcrumb":{"@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/#primaryimage","url":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC.jpg","contentUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/05\/OMC.jpg","width":360,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/amiti.org.mx\/12668\/amiti-participa-en-taller-de-la-omc-sobre-la-moratoria-a-los-derechos-aduaneros-en-transmisiones-electronicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amiti.org.mx\/"},{"@type":"ListItem","position":2,"name":"AMITI participa en Taller de la OMC sobre la Moratoria a los Derechos Aduaneros en Transmisiones Electr\u00f3nicas"}]},{"@type":"WebSite","@id":"https:\/\/amiti.org.mx\/#website","url":"https:\/\/amiti.org.mx\/","name":"AMITI","description":"Mejores empresas TI para M\u00e9xico","publisher":{"@id":"https:\/\/amiti.org.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amiti.org.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/amiti.org.mx\/#organization","name":"AMITI","url":"https:\/\/amiti.org.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/amiti.org.mx\/#\/schema\/logo\/image\/","url":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/09\/Amiti_CMYK.png","contentUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/09\/Amiti_CMYK.png","width":1161,"height":458,"caption":"AMITI"},"image":{"@id":"https:\/\/amiti.org.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AMITIMex\/?locale=es_LA","https:\/\/x.com\/AMITI_Mex","https:\/\/www.instagram.com\/amiti_mex\/","https:\/\/www.linkedin.com\/company\/amiti-mex\/","https:\/\/www.youtube.com\/channel\/UCaBdZB-k6j-lCH-eTCbLGJw"]},{"@type":"Person","@id":"https:\/\/amiti.org.mx\/#\/schema\/person\/09fd614b7d440b5ba06c0480ed768000","name":"Heidy-O","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g","caption":"Heidy-O"},"url":"https:\/\/amiti.org.mx\/en\/author\/heidy-o\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:04:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts\/12668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/users\/148"}],"replies":[{"embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/comments?post=12668"}],"version-history":[{"count":2,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts\/12668\/revisions"}],"predecessor-version":[{"id":12675,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts\/12668\/revisions\/12675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/media\/12669"}],"wp:attachment":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/media?parent=12668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/categories?post=12668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/tags?post=12668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}