{"id":12295,"date":"2025-02-18T09:59:00","date_gmt":"2025-02-18T09:59:00","guid":{"rendered":"https:\/\/amiti.org.mx\/?p=12295"},"modified":"2025-02-18T15:45:58","modified_gmt":"2025-02-18T15:45:58","slug":"declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec","status":"publish","type":"post","link":"https:\/\/amiti.org.mx\/en\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/","title":{"rendered":"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><em>18 de febrero de 2025<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"630\" height=\"66\" src=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/asociaciones.jpg\" alt=\"\" class=\"wp-image-12296\" srcset=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/asociaciones.jpg 630w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/asociaciones-300x31.jpg 300w, https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/asociaciones-18x2.jpg 18w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nosotros, las asociaciones tecnol\u00f3gicas firmantes que representamos al sector tecnol\u00f3gico en toda Am\u00e9rica del Norte, instamos a los responsables de las pol\u00edticas a priorizar los esfuerzos para renovar el Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (T-MEC), asegurando que siga impulsando el crecimiento econ\u00f3mico, la innovaci\u00f3n y la seguridad en nuestras tres naciones. Nuestras organizaciones representan una amplia variedad de empresas de alta tecnolog\u00eda y basadas en tecnolog\u00eda, desde startups hasta corporaciones multinacionales, que operan en toda Am\u00e9rica del Norte y contribuyen al liderazgo econ\u00f3mico y tecnol\u00f3gico de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El T-MEC ha desempe\u00f1ado un papel crucial en la promoci\u00f3n de un entorno comercial estable y predecible, permitiendo un crecimiento significativo en la inversi\u00f3n transfronteriza, fortaleciendo las cadenas de suministro regionales y mejorando la colaboraci\u00f3n en tecnolog\u00edas emergentes. Al facilitar el acceso a los mercados y reducir barreras, el tratado ha apoyado la creaci\u00f3n de empleos, la innovaci\u00f3n tecnol\u00f3gica y la resiliencia econ\u00f3mica en las tres econom\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las normas de alto est\u00e1ndar sobre comercio digital en el T-MEC han sido de vital importancia para la econom\u00eda, dado el r\u00e1pido crecimiento de las oportunidades en el comercio digital y la proliferaci\u00f3n de barreras digitales en todo el mundo. El cap\u00edtulo sobre comercio digital proporciona una base para que las empresas operen de manera m\u00e1s eficiente y efectiva, al promover el libre flujo de datos y servicios digitales a trav\u00e9s de las fronteras y garantizar que las empresas puedan competir en igualdad de condiciones en la regi\u00f3n. El pr\u00f3ximo proceso de revisi\u00f3n del T-MEC brinda una oportunidad para que los pa\u00edses aborden los desaf\u00edos de cumplimiento e implementaci\u00f3n y garanticen que se respete el esp\u00edritu del acuerdo, adem\u00e1s de atender los problemas actuales. Alentamos a los gobiernos a llevar a cabo un proceso de revisi\u00f3n que incluya una participaci\u00f3n regular y significativa de las partes interesadas del sector privado y que considere la naturaleza cambiante de la econom\u00eda digital para enfrentar los desaf\u00edos emergentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una econom\u00eda norteamericana s\u00f3lida es esencial para la competitividad individual y colectiva de nuestros pa\u00edses en el panorama tecnol\u00f3gico global. El T-MEC ha sido una herramienta valiosa para promover el crecimiento econ\u00f3mico y el avance tecnol\u00f3gico en la regi\u00f3n. Les instamos a renovar el T-MEC y a trabajar para garantizar que el acuerdo contin\u00fae brindando beneficios a las empresas, los trabajadores y los consumidores en toda la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agradecemos su atenci\u00f3n a este asunto importante y estamos listos para apoyarlos en este proceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sinceramente,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asociaci\u00f3n Mexicana de la Industria de Tecnolog\u00edas de Informaci\u00f3n &#8211; AMITI<br>Information Technology Industry Council &#8211; ITI<br>TECHNATION<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><a href=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/Declaracion-de-la-Industria-Tecnologica-de-America-del-Norte-sobre-la-Renovacion-del-T-MEC.pdf\">DESCARGA COMUNICADO<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>North American Tech Industry Statement on USMCA Renewal<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>February 18, 2025<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We, the undersigned technology associations representing the technology sector across North America, urge policymakers to prioritize efforts to renew the United States-Mexico-Canada Agreement (USMCA) ensuring that it continues to drive economic growth, innovation, and security across our three nations. Our organizations represent a diverse range of high-tech and tech-enabled companies\u2014from startups to multinational corporations\u2014operating across North America and contributing to the region\u2019s economic and technological leadership.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The USMCA has played a crucial role in fostering a stable and predictable trade environment enabling significant growth in cross-border investment, strengthening regional supply chains, and enhancing collaboration in emerging technologies. By facilitating market access and reducing barriers, the agreement has supported job creation, technological innovation, and economic resilience across all three economies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The high-standard digital trade rules in USMCA have been of critical importance to the economy, given the rapid growth of digital trade opportunities and the spread of digital trade barriers around the world. The digital trade chapter provides an underpinning for companies to operate more efficiently and effectively by promoting the free flow of data and digital services across borders and ensuring that companies can compete fairly in the region. The upcoming USMCA review process provides an opportunity for countries to address compliance and implementation challenges to ensure the spirit of the agreement is upheld and to address current issues. We encourage the governments to conduct a review process that involves regular and meaningful private sector stakeholder engagement and partnership, and consider the evolving nature of the digital economy to address emerging challenges.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A robust North American economy is essential for our countries\u2019 individual and collective competitiveness in the global technology landscape. The USMCA has been a valuable instrument for promoting economic growth and technological advancement in the region. We urge you to renew the USMCA and work towards ensuring that the agreement continues to deliver benefits for businesses, workers, and consumers across the region.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We are grateful for your attention to this important matter and stand ready to assist you in this process. Sincerely,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asociaci\u00f3n Mexicana de la Industria de Tecnolog\u00edas de Informaci\u00f3n &#8211; AMITI <br>Information Technology Industry Council &#8211; ITI<br>TECHNATION<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/North-American-Tech-Industry-Statement-on-USMCA-Renewal_Feb-2025_date.pdf\"><strong>DOWNLOAD COMMUNICATION<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>18 de febrero de 2025 Nosotros, las asociaciones tecnol\u00f3gicas firmantes que representamos al sector tecnol\u00f3gico en toda Am\u00e9rica del Norte, instamos a los responsables de las pol\u00edticas a priorizar los esfuerzos para renovar el Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (T-MEC), asegurando que siga impulsando el crecimiento econ\u00f3mico, la innovaci\u00f3n y la seguridad en [&hellip;]<\/p>\n","protected":false},"author":148,"featured_media":12298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-12295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-amiti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC - AMITI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amiti.org.mx\/en\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC - AMITI\" \/>\n<meta property=\"og:description\" content=\"18 de febrero de 2025 Nosotros, las asociaciones tecnol\u00f3gicas firmantes que representamos al sector tecnol\u00f3gico en toda Am\u00e9rica del Norte, instamos a los responsables de las pol\u00edticas a priorizar los esfuerzos para renovar el Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (T-MEC), asegurando que siga impulsando el crecimiento econ\u00f3mico, la innovaci\u00f3n y la seguridad en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amiti.org.mx\/en\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/\" \/>\n<meta property=\"og:site_name\" content=\"AMITI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AMITIMex\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T09:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T15:45:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/TMEC_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heidy-O\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AMITI_Mex\" \/>\n<meta name=\"twitter:site\" content=\"@AMITI_Mex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heidy-O\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/\"},\"author\":{\"name\":\"Heidy-O\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/person\\\/09fd614b7d440b5ba06c0480ed768000\"},\"headline\":\"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC\",\"datePublished\":\"2025-02-18T09:59:00+00:00\",\"dateModified\":\"2025-02-18T15:45:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/\"},\"wordCount\":868,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/TMEC_web.jpg\",\"articleSection\":[\"Noticias AMITI\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/\",\"name\":\"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC - AMITI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/TMEC_web.jpg\",\"datePublished\":\"2025-02-18T09:59:00+00:00\",\"dateModified\":\"2025-02-18T15:45:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/TMEC_web.jpg\",\"contentUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/TMEC_web.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/12295\\\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amiti.org.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#website\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/\",\"name\":\"AMITI\",\"description\":\"Mejores empresas TI para M\u00e9xico\",\"publisher\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amiti.org.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#organization\",\"name\":\"AMITI\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Amiti_CMYK.png\",\"contentUrl\":\"https:\\\/\\\/amiti.org.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Amiti_CMYK.png\",\"width\":1161,\"height\":458,\"caption\":\"AMITI\"},\"image\":{\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AMITIMex\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/AMITI_Mex\",\"https:\\\/\\\/www.instagram.com\\\/amiti_mex\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/amiti-mex\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCaBdZB-k6j-lCH-eTCbLGJw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amiti.org.mx\\\/#\\\/schema\\\/person\\\/09fd614b7d440b5ba06c0480ed768000\",\"name\":\"Heidy-O\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g\",\"caption\":\"Heidy-O\"},\"url\":\"https:\\\/\\\/amiti.org.mx\\\/en\\\/author\\\/heidy-o\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC - AMITI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amiti.org.mx\/en\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/","og_locale":"en_US","og_type":"article","og_title":"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC - AMITI","og_description":"18 de febrero de 2025 Nosotros, las asociaciones tecnol\u00f3gicas firmantes que representamos al sector tecnol\u00f3gico en toda Am\u00e9rica del Norte, instamos a los responsables de las pol\u00edticas a priorizar los esfuerzos para renovar el Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (T-MEC), asegurando que siga impulsando el crecimiento econ\u00f3mico, la innovaci\u00f3n y la seguridad en [&hellip;]","og_url":"https:\/\/amiti.org.mx\/en\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/","og_site_name":"AMITI","article_publisher":"https:\/\/www.facebook.com\/AMITIMex\/?locale=es_LA","article_published_time":"2025-02-18T09:59:00+00:00","article_modified_time":"2025-02-18T15:45:58+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/TMEC_web.jpg","type":"image\/jpeg"}],"author":"Heidy-O","twitter_card":"summary_large_image","twitter_creator":"@AMITI_Mex","twitter_site":"@AMITI_Mex","twitter_misc":{"Written by":"Heidy-O","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/#article","isPartOf":{"@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/"},"author":{"name":"Heidy-O","@id":"https:\/\/amiti.org.mx\/#\/schema\/person\/09fd614b7d440b5ba06c0480ed768000"},"headline":"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC","datePublished":"2025-02-18T09:59:00+00:00","dateModified":"2025-02-18T15:45:58+00:00","mainEntityOfPage":{"@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/"},"wordCount":868,"commentCount":0,"publisher":{"@id":"https:\/\/amiti.org.mx\/#organization"},"image":{"@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/#primaryimage"},"thumbnailUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/TMEC_web.jpg","articleSection":["Noticias AMITI"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/","url":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/","name":"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC - AMITI","isPartOf":{"@id":"https:\/\/amiti.org.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/#primaryimage"},"image":{"@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/#primaryimage"},"thumbnailUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/TMEC_web.jpg","datePublished":"2025-02-18T09:59:00+00:00","dateModified":"2025-02-18T15:45:58+00:00","breadcrumb":{"@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/#primaryimage","url":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/TMEC_web.jpg","contentUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2025\/02\/TMEC_web.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/amiti.org.mx\/12295\/declaracion-de-la-industria-tecnologica-de-america-del-norte-sobre-la-renovacion-del-t-mec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amiti.org.mx\/"},{"@type":"ListItem","position":2,"name":"Declaraci\u00f3n de la Industria Tecnol\u00f3gica de Am\u00e9rica del Norte sobre la Renovaci\u00f3n del T-MEC"}]},{"@type":"WebSite","@id":"https:\/\/amiti.org.mx\/#website","url":"https:\/\/amiti.org.mx\/","name":"AMITI","description":"Mejores empresas TI para M\u00e9xico","publisher":{"@id":"https:\/\/amiti.org.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amiti.org.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/amiti.org.mx\/#organization","name":"AMITI","url":"https:\/\/amiti.org.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/amiti.org.mx\/#\/schema\/logo\/image\/","url":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/09\/Amiti_CMYK.png","contentUrl":"https:\/\/amiti.org.mx\/wp-content\/uploads\/2024\/09\/Amiti_CMYK.png","width":1161,"height":458,"caption":"AMITI"},"image":{"@id":"https:\/\/amiti.org.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AMITIMex\/?locale=es_LA","https:\/\/x.com\/AMITI_Mex","https:\/\/www.instagram.com\/amiti_mex\/","https:\/\/www.linkedin.com\/company\/amiti-mex\/","https:\/\/www.youtube.com\/channel\/UCaBdZB-k6j-lCH-eTCbLGJw"]},{"@type":"Person","@id":"https:\/\/amiti.org.mx\/#\/schema\/person\/09fd614b7d440b5ba06c0480ed768000","name":"Heidy-O","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6bb82f883f01a117ffeab0847eb3d1e1bc043d3f57c214a17dde7220e395cb0d?s=96&d=mm&r=g","caption":"Heidy-O"},"url":"https:\/\/amiti.org.mx\/en\/author\/heidy-o\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 04:04:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts\/12295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/users\/148"}],"replies":[{"embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/comments?post=12295"}],"version-history":[{"count":2,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts\/12295\/revisions"}],"predecessor-version":[{"id":12303,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/posts\/12295\/revisions\/12303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/media\/12298"}],"wp:attachment":[{"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/media?parent=12295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/categories?post=12295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amiti.org.mx\/en\/wp-json\/wp\/v2\/tags?post=12295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}